{"id":19670,"date":"2024-04-08T18:35:25","date_gmt":"2024-04-08T18:35:25","guid":{"rendered":"https:\/\/natwineaficionados.com\/?post_type=product&#038;p=19670"},"modified":"2026-08-26T11:23:51","modified_gmt":"2026-08-26T11:23:51","slug":"collezione-vitovska-2016","status":"publish","type":"product","link":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/","title":{"rendered":"Collezione Vitovska 2016"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Vino elaborado \u00fanicamente en los mejores a\u00f1os (2006, 2009, 2015 y 2016) que ejemplifica la expresi\u00f3n m\u00e1xima de lo que la vitovska puede dar. Es una experiencia intensa, poderosa y al mismo tiempo elegante. Su degustaci\u00f3n es un desaf\u00edo para los sentidos y su plena comprensi\u00f3n exige concentraci\u00f3n y recogimiento. Estamos ante una obra maestra de la Naturaleza y del Hombre. Un vino tan fascinante como raro.<\/p>\n","protected":false},"featured_media":15461,"template":"","meta":[],"product_brand":[],"product_cat":[612,306,429,291,271],"product_tag":[],"class_list":["post-19670","product","type-product","status-publish","has-post-thumbnail","product_cat-2016-es","product_cat-agricultura-biodinamica-es","product_cat-italia-es","product_cat-naranjas-es-es","product_cat-sin-sulfitos-anadidos-es","bsb_wine_producer-azienda-zidarich-es","bsb_wine_color-naranjas-es-es","bsb_wine_country-italia-es","bsb_wine_region-friuli-venecia-julia-es","bsb_wine_grape-vitovska-es","bsb_wine_year-2016-es","bsb_wine_farming-agricultura-biodinamica-linked","bsb_wine_farming-sin-sulfitos-anadidos-linked","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collezione Vitovska 2016 | Natwine Aficionados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collezione Vitovska 2016 | Natwine Aficionados\" \/>\n<meta property=\"og:description\" content=\"Vino elaborado \u00fanicamente en los mejores a\u00f1os (2006, 2009, 2015 y 2016) que ejemplifica la expresi\u00f3n m\u00e1xima de lo que la vitovska puede dar. Es una experiencia intensa, poderosa y al mismo tiempo elegante. Su degustaci\u00f3n es un desaf\u00edo para los sentidos y su plena comprensi\u00f3n exige concentraci\u00f3n y recogimiento. Estamos ante una obra maestra de la Naturaleza y del Hombre. Un vino tan fascinante como raro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Natwine Aficionados\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-26T11:23:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natwineaficionados.com\/wp-content\/uploads\/2024\/04\/Zidarich-Vitovska-2016-collection-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/\",\"url\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/\",\"name\":\"Collezione Vitovska 2016 | Natwine Aficionados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natwineaficionados.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Zidarich-Vitovska-2016-collection-1.jpg\",\"datePublished\":\"2024-04-08T18:35:25+00:00\",\"dateModified\":\"2026-08-26T11:23:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/natwineaficionados.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Zidarich-Vitovska-2016-collection-1.jpg\",\"contentUrl\":\"https:\\\/\\\/natwineaficionados.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Zidarich-Vitovska-2016-collection-1.jpg\",\"width\":2160,\"height\":2160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/produtos\\\/collezione-vitovska-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/natwineaficionados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/natwineaficionados.com\\\/es\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collezione Vitovska 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natwineaficionados.com\\\/#website\",\"url\":\"https:\\\/\\\/natwineaficionados.com\\\/\",\"name\":\"Natwine Aficionados\",\"description\":\"A sua Loja online de Vinhos Naturais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natwineaficionados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collezione Vitovska 2016 | Natwine Aficionados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/","og_locale":"es_ES","og_type":"article","og_title":"Collezione Vitovska 2016 | Natwine Aficionados","og_description":"Vino elaborado \u00fanicamente en los mejores a\u00f1os (2006, 2009, 2015 y 2016) que ejemplifica la expresi\u00f3n m\u00e1xima de lo que la vitovska puede dar. Es una experiencia intensa, poderosa y al mismo tiempo elegante. Su degustaci\u00f3n es un desaf\u00edo para los sentidos y su plena comprensi\u00f3n exige concentraci\u00f3n y recogimiento. Estamos ante una obra maestra de la Naturaleza y del Hombre. Un vino tan fascinante como raro.","og_url":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/","og_site_name":"Natwine Aficionados","article_modified_time":"2026-08-26T11:23:51+00:00","og_image":[{"width":2160,"height":2160,"url":"https:\/\/natwineaficionados.com\/wp-content\/uploads\/2024\/04\/Zidarich-Vitovska-2016-collection-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/","url":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/","name":"Collezione Vitovska 2016 | Natwine Aficionados","isPartOf":{"@id":"https:\/\/natwineaficionados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/#primaryimage"},"image":{"@id":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/natwineaficionados.com\/wp-content\/uploads\/2024\/04\/Zidarich-Vitovska-2016-collection-1.jpg","datePublished":"2024-04-08T18:35:25+00:00","dateModified":"2026-08-26T11:23:51+00:00","breadcrumb":{"@id":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/#primaryimage","url":"https:\/\/natwineaficionados.com\/wp-content\/uploads\/2024\/04\/Zidarich-Vitovska-2016-collection-1.jpg","contentUrl":"https:\/\/natwineaficionados.com\/wp-content\/uploads\/2024\/04\/Zidarich-Vitovska-2016-collection-1.jpg","width":2160,"height":2160},{"@type":"BreadcrumbList","@id":"https:\/\/natwineaficionados.com\/es\/produtos\/collezione-vitovska-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/natwineaficionados.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/natwineaficionados.com\/es\/loja\/"},{"@type":"ListItem","position":3,"name":"Collezione Vitovska 2016"}]},{"@type":"WebSite","@id":"https:\/\/natwineaficionados.com\/#website","url":"https:\/\/natwineaficionados.com\/","name":"Natwine Aficionados","description":"A sua Loja online de Vinhos Naturais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natwineaficionados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/product\/19670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/product\/19670\/revisions"}],"predecessor-version":[{"id":19672,"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/product\/19670\/revisions\/19672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/media\/15461"}],"wp:attachment":[{"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/media?parent=19670"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/product_brand?post=19670"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/product_cat?post=19670"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/natwineaficionados.com\/es\/wp-json\/wp\/v2\/product_tag?post=19670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}